{"id":10124,"date":"2026-05-07T10:15:00","date_gmt":"2026-05-07T13:15:00","guid":{"rendered":"https:\/\/acriticatrends.audiencelabs.com.br\/?p=10124"},"modified":"2026-05-07T09:10:57","modified_gmt":"2026-05-07T12:10:57","slug":"nova-fabrica-de-r-205-milhoes-vai-usar-tecnologia-que-reduz-processo-de-fabricacao-de-3-horas-para-apenas-3-minutos","status":"publish","type":"post","link":"https:\/\/acriticatrends.audiencelabs.com.br\/nova-fabrica-de-r-205-milhoes-vai-usar-tecnologia-que-reduz-processo-de-fabricacao-de-3-horas-para-apenas-3-minutos\/","title":{"rendered":"Nova f\u00e1brica de R$ 205 milh\u00f5es vai usar tecnologia que reduz processo de fabrica\u00e7\u00e3o de 3 horas para apenas 3 minutos"},"content":{"rendered":"\n<p>Uma nova f\u00e1brica de custo milion\u00e1rio vai impactar diretamente a economia de Joinville, a maior cidade de Santa Catarina. Visando expandir sua atua\u00e7\u00e3o no setor de molas no territ\u00f3rio brasileiro, a alem\u00e3 Schom\u00e4cker ir\u00e1 se instalar no Perini Business Park.<\/p>\n\n\n\n<p>O empreendimento ter\u00e1 um investimento inicial de R$ 205 milh\u00f5es e ir\u00e1 gerar 105 empregos diretos. Ser\u00e1 o primeiro no Brasil a produzir molas, alavancas, barras estabilizadoras e outros acess\u00f3rios tanto para o mercado nacional quanto para exporta\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Nesta quarta-feira (6), o governador Jorginho Mello e o s\u00f3cio-administrador da Schom\u00e4cker, Joachim Henrich Wilhelm Sommer, assinaram um termo de coopera\u00e7\u00e3o para oficializar a chegada da multinacional ao munic\u00edpio catarinense. O documento estabelece o apoio do governo em frentes essenciais para o sucesso do projeto.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Schomacker-em-Joinville-Foto-Schomacker-Divulgacao-944x531.jpg-1024x576.jpg\" alt=\"\" class=\"wp-image-10125\" srcset=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Schomacker-em-Joinville-Foto-Schomacker-Divulgacao-944x531.jpg-1024x576.jpg 1024w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Schomacker-em-Joinville-Foto-Schomacker-Divulgacao-944x531.jpg-300x169.jpg 300w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Schomacker-em-Joinville-Foto-Schomacker-Divulgacao-944x531.jpg-768x432.jpg 768w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Schomacker-em-Joinville-Foto-Schomacker-Divulgacao-944x531.jpg-750x422.jpg 750w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Schomacker-em-Joinville-Foto-Schomacker-Divulgacao-944x531.jpg-1140x641.jpg 1140w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Schomacker-em-Joinville-Foto-Schomacker-Divulgacao-944x531.jpg.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Schom\u00e4cker<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O apoio estadual constar\u00e1 na facilita\u00e7\u00e3o log\u00edstica e na identifica\u00e7\u00e3o de fornecedores locais atrav\u00e9s da Invest SC, empresa p\u00fablica de atra\u00e7\u00e3o de investimentos. Segundo o Governo de Santa Catarina, a assinatura representa seguran\u00e7a institucional ao investidor estrangeiro.<\/p>\n\n\n\n<p>O governo espera que a f\u00e1brica gere R$ 339 milh\u00f5es em receitas, com possibilidade de expans\u00e3o a curto prazo. A Schom\u00e4cker prev\u00ea injetar mais R$ 317 milh\u00f5es na opera\u00e7\u00e3o local nos pr\u00f3ximos cinco anos e projeta um aumento de quase 100% no quadro de funcion\u00e1rios at\u00e9 2031.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Produ\u00e7\u00e3o de pe\u00e7as em 3 minutos<\/h2>\n\n\n\n<p>A Schom\u00e4cker chega a Joinville com uma estrutura formada por equipamentos exclusivos e engenharia de excel\u00eancia para produzir itens \u00fanicos no mercado. De acordo com o s\u00f3cio-administrador da empresa alem\u00e3, uma nova tecnologia reduz o tempo de produ\u00e7\u00e3o que j\u00e1 foi de tr\u00eas horas para apenas tr\u00eas minutos.<\/p>\n\n\n\n<p>\u201cN\u00f3s estamos trazendo uma tecnologia inovadora e que reduziu um processo de fabrica\u00e7\u00e3o que levava 3 horas para apenas 3 minutos por pe\u00e7a. N\u00f3s fabricamos as nossas pr\u00f3prias m\u00e1quinas usadas nesse processo inovador\u201d, explicou Joachim Henrich Wilhelm Sommer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma nova f\u00e1brica de custo milion\u00e1rio vai impactar diretamente a economia de Joinville, a maior cidade de Santa Catarina. Visando expandir sua atua\u00e7\u00e3o no setor de molas no territ\u00f3rio brasileiro, a alem\u00e3 Schom\u00e4cker ir\u00e1 se instalar no Perini Business Park. O empreendimento ter\u00e1 um investimento inicial de R$ 205 milh\u00f5es e ir\u00e1 gerar 105 empregos [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":10126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[55],"tags":[],"class_list":["post-10124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trends"],"_links":{"self":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=10124"}],"version-history":[{"count":1,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10124\/revisions"}],"predecessor-version":[{"id":10127,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10124\/revisions\/10127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/10126"}],"wp:attachment":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=10124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=10124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=10124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}