{"id":10674,"date":"2026-05-13T16:45:00","date_gmt":"2026-05-13T19:45:00","guid":{"rendered":"https:\/\/acriticatrends.audiencelabs.com.br\/?p=10674"},"modified":"2026-05-13T11:52:31","modified_gmt":"2026-05-13T14:52:31","slug":"ricaco-famoso-no-brasil-separa-r-532-bilhoes-para-ajudar-os-pobres","status":"publish","type":"post","link":"https:\/\/acriticatrends.audiencelabs.com.br\/ricaco-famoso-no-brasil-separa-r-532-bilhoes-para-ajudar-os-pobres\/","title":{"rendered":"Rica\u00e7o famoso no Brasil separa R$ 532 bilh\u00f5es para ajudar os pobres"},"content":{"rendered":"\n<p>De acordo com proje\u00e7\u00f5es de especialistas, para acabar com a fome no mundo seria necess\u00e1rio um investimento estimado entre US$ 37 bilh\u00f5es (cerca de R$ 182,5 bilh\u00f5es) e US$ 267 bilh\u00f5es (R$ 1,3 trilh\u00e3o) por ano at\u00e9 2030. Mesmo que os valores n\u00e3o sejam compat\u00edveis com a realidade, um vision\u00e1rio norte-americano garantiu que pretende contribuir com o plano audacioso.<\/p>\n\n\n\n<p>Consolidado por ter fundado a Microsoft, uma das maiores empresas de tecnologia do planeta, Bill Gates anunciou que vai doar 99% de sua fortuna pessoal, atualmente estimada em US$ 108 bilh\u00f5es (cerca de R$ 532,8 bilh\u00f5es). Segundo as suas previs\u00f5es, a ideia \u00e9 abrir m\u00e3o do dinheiro ao longo das pr\u00f3ximas duas d\u00e9cadas, por meio da Gates Foundation, organiza\u00e7\u00e3o que criou para combater doen\u00e7as e pobreza extrema.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Bill-Gates-e1743128422755-1024x576.jpg\" alt=\"\" class=\"wp-image-10679\" srcset=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Bill-Gates-e1743128422755-1024x576.jpg 1024w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Bill-Gates-e1743128422755-300x169.jpg 300w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Bill-Gates-e1743128422755-768x432.jpg 768w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Bill-Gates-e1743128422755-750x422.jpg 750w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Bill-Gates-e1743128422755-1140x641.jpg 1140w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Bill-Gates-e1743128422755.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Todd Owyoung\/NBC<\/figcaption><\/figure>\n\n\n\n<p>Reconhecendo a necessidade de mudar o mundo com o patrim\u00f4nio acumulado, o bilion\u00e1rio aclamado no <a href=\"https:\/\/www.acritica.com\/trends\/unico-trem-diario-para-passageiros-no-brasil-passa-por-40-municipios-e-liga-dois-estados\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brasil <\/a>tamb\u00e9m afirmou que, al\u00e9m das suas doa\u00e7\u00f5es \u00e0 funda\u00e7\u00e3o, aproximadamente US$ 200 bilh\u00f5es (R$ 986,8 bilh\u00f5es, na convers\u00e3o atual) ser\u00e3o destinados \u00e0s popula\u00e7\u00f5es mais pobres do mundo em um trabalho a ser sacramentado at\u00e9 2045.<\/p>\n\n\n\n<p id=\"paragrafo-0mhxz0magr\">Curiosamente, Bill n\u00e3o deixar\u00e1 sua fortuna nas m\u00e3os dos tr\u00eas filhos. Isso porque, na an\u00e1lise do empres\u00e1rio, entregar grandes quantias em dinheiro pode limitar a independ\u00eancia e constru\u00e7\u00e3o da pr\u00f3pria\u00a0trajet\u00f3ria profissional\u00a0dos herdeiros. Nesse intervalo, a pretens\u00e3o \u00e9 destinar parcela do patrim\u00f4nio para a\u00e7\u00f5es filantr\u00f3picas, enquanto os filhos receberiam apenas uma parcela considerada suficiente para terem conforto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mas, afinal, quem s\u00e3o as pessoas mais ricas do Brasil?<\/h2>\n\n\n\n<p>Embora o prest\u00edgio financeiro de Bill Gates esteja longe de ser alcan\u00e7ado por empres\u00e1rios do Brasil, no pa\u00eds h\u00e1 vision\u00e1rios com proje\u00e7\u00f5es audaciosas. Segundo a revista Forbes, o brasileiro mais rico da atualidade \u00e9 Eduardo Saverin, conhecido mundialmente por ser um dos cofundadores do Facebook (hoje Meta Platforms).<\/p>\n\n\n\n<p>Confira a lista dos brasileiros mais afortunados:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1\u00ba lugar: <strong>Eduardo Saverin \u2014\u00a0<strong>US$ 35,9 bilh\u00f5es<\/strong><\/strong>;<\/li>\n\n\n\n<li>2\u00ba lugar: Andr\u00e9 Esteves \u2014\u00a0<strong>US$ 20,2 bilh\u00f5es<\/strong>;<\/li>\n\n\n\n<li>3\u00ba lugar: Jorge Paulo Lemann \u2014\u00a0<strong>US$ 19,8 bilh\u00f5es;<\/strong><\/li>\n\n\n\n<li>4\u00ba lugar: Fernando Roberto Moreira Salles \u2014\u00a0<strong>US$ 9,9 bilh\u00f5es;<\/strong><\/li>\n\n\n\n<li>5\u00ba lugar: Pedro Moreira Salles \u2014<strong>\u00a0US$ 9,1 bilh\u00f5es<\/strong>;<\/li>\n\n\n\n<li>6\u00ba lugar: Jorge Moll Filho \u2014\u00a0<strong>US$ 7,5 bilh\u00f5es<\/strong>;<\/li>\n\n\n\n<li>7\u00ba lugar: Max Van Hoegaerden Herrmann Telles \u2014<strong>\u00a0US$ 7,4 bilh\u00f5es;<\/strong><\/li>\n\n\n\n<li>8\u00ba lugar: Carlos Alberto Sicupira \u2014\u00a0<strong>US$ 6,9 bilh\u00f5es<\/strong>;<\/li>\n\n\n\n<li>9\u00ba lugar: Miguel Krigsner \u2014\u00a0<strong>US$ 6,8 bilh\u00f5es<\/strong>;<\/li>\n\n\n\n<li>10\u00ba lugar: Alex Behring \u2014\u00a0<strong>US$ 5,8 bilh\u00f5es<\/strong>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Reconhecendo a necessidade de mudar o mundo com o patrim\u00f4nio acumulado, o bilion\u00e1rio aclamado no Brasil tamb\u00e9m afirmou que, al\u00e9m das suas doa\u00e7\u00f5es \u00e0 funda\u00e7\u00e3o, aproximadamente US$ 200 bilh\u00f5es (R$ 986,8 bilh\u00f5es, na convers\u00e3o atual) ser\u00e3o destinados \u00e0s popula\u00e7\u00f5es mais pobres do mundo em um trabalho a ser sacramentado at\u00e9 2045.<\/p>\n","protected":false},"author":14,"featured_media":10681,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[55],"tags":[],"class_list":["post-10674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trends"],"_links":{"self":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=10674"}],"version-history":[{"count":1,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10674\/revisions"}],"predecessor-version":[{"id":10684,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10674\/revisions\/10684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/10681"}],"wp:attachment":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=10674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=10674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=10674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}