{"id":10692,"date":"2026-05-13T17:15:00","date_gmt":"2026-05-13T20:15:00","guid":{"rendered":"https:\/\/acriticatrends.audiencelabs.com.br\/?p=10692"},"modified":"2026-05-13T12:40:39","modified_gmt":"2026-05-13T15:40:39","slug":"apos-anunciar-hulk-interesse-do-fluminense-em-outro-atacante-e-revelado","status":"publish","type":"post","link":"https:\/\/acriticatrends.audiencelabs.com.br\/apos-anunciar-hulk-interesse-do-fluminense-em-outro-atacante-e-revelado\/","title":{"rendered":"Ap\u00f3s anunciar Hulk, interesse do Fluminense em outro atacante \u00e9 revelado"},"content":{"rendered":"\n<p>Ap\u00f3s anunciar Hulk como refor\u00e7o para a sequ\u00eancia da temporada, o Fluminense tamb\u00e9m teve outro nome ligado ao setor ofensivo revelado nos bastidores. O interesse do clube carioca em mais um atacante veio \u00e0 tona justamente ap\u00f3s declara\u00e7\u00f5es envolvendo uma tentativa de contrata\u00e7\u00e3o feita ainda em 2025.<\/p>\n\n\n\n<p>O jogador citado foi <strong>Rafael Navarro<\/strong>, ex-Palmeiras e atualmente no Colorado Rapids, dos Estados Unidos. Em entrevista ao ge, o atacante confirmou que houve contato do Fluminense e que o clube chegou at\u00e9 mesmo a apresentar uma proposta oficial durante aquele per\u00edodo da temporada.<\/p>\n\n\n\n<p>Segundo Rafael Navarro, o Colorado Rapids preferiu n\u00e3o avan\u00e7ar nas negocia\u00e7\u00f5es naquele momento. Isso porque a equipe vivia uma situa\u00e7\u00e3o importante envolvendo a disputa por classifica\u00e7\u00e3o aos playoffs, fator que acabou dificultando uma poss\u00edvel sa\u00edda do brasileiro.<\/p>\n\n\n\n<p>O atacante tamb\u00e9m destacou a satisfa\u00e7\u00e3o por despertar interesse de um clube do tamanho do Fluminense. Revelado nas categorias de base do pr\u00f3prio Tricolor, Navarro ganhou destaque nacional justamente defendendo o Botafogo na campanha de acesso para a S\u00e9rie A em 2021.<\/p>\n\n\n\n<p>Depois disso, o jogador acertou com o Palmeiras em 2022, mas n\u00e3o conseguiu ter grande sequ\u00eancia. J\u00e1 em julho de 2023, acabou sendo emprestado ao Colorado Rapids, clube que posteriormente confirmou a compra definitiva do atacante no ano seguinte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Rafael-Navarro-em-acao-pelo-Rapids-1-1024x576.jpg\" alt=\"\" class=\"wp-image-10694\" srcset=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Rafael-Navarro-em-acao-pelo-Rapids-1-1024x576.jpg 1024w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Rafael-Navarro-em-acao-pelo-Rapids-1-300x169.jpg 300w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Rafael-Navarro-em-acao-pelo-Rapids-1-768x432.jpg 768w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Rafael-Navarro-em-acao-pelo-Rapids-1-750x422.jpg 750w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Rafael-Navarro-em-acao-pelo-Rapids-1-1140x641.jpg 1140w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/Rafael-Navarro-em-acao-pelo-Rapids-1.jpg 1245w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Colorado Rapids<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Boa temporada de Rafael Navarro<\/h2>\n\n\n\n<p>Na atual temporada, Rafael Navarro soma 14 partidas pelo Colorado Rapids, com sete gols marcados e cinco assist\u00eancias distribu\u00eddas. O atacante afirmou, inclusive, que este pode ser o melhor in\u00edcio de temporada de toda a sua carreira profissional at\u00e9 aqui.<\/p>\n\n\n\n<p>Al\u00e9m dos n\u00fameros positivos, o jogador destacou a felicidade por contribuir ofensivamente com frequ\u00eancia. Justamente por isso, Rafael Navarro tamb\u00e9m afirmou que espera alcan\u00e7ar marcas ainda maiores ao longo da temporada, buscando aumentar a quantidade de gols e assist\u00eancias nos pr\u00f3ximos jogos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s anunciar Hulk como refor\u00e7o para a sequ\u00eancia da temporada, o Fluminense tamb\u00e9m teve outro nome ligado ao setor ofensivo revelado nos bastidores. O interesse do clube carioca em mais um atacante veio \u00e0 tona justamente ap\u00f3s declara\u00e7\u00f5es envolvendo uma tentativa de contrata\u00e7\u00e3o feita ainda em 2025. O jogador citado foi Rafael Navarro, ex-Palmeiras e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10693,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[55],"tags":[],"class_list":["post-10692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trends"],"_links":{"self":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=10692"}],"version-history":[{"count":1,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10692\/revisions"}],"predecessor-version":[{"id":10695,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10692\/revisions\/10695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/10693"}],"wp:attachment":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=10692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=10692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=10692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}