{"id":8098,"date":"2026-04-16T10:52:00","date_gmt":"2026-04-16T13:52:00","guid":{"rendered":"https:\/\/acriticatrends.audiencelabs.com.br\/?p=8098"},"modified":"2026-04-16T09:29:49","modified_gmt":"2026-04-16T12:29:49","slug":"13o-salario-antecipado-aposentados-sao-avisados-sobre-liberacao-no-aplicativo-meu-inss","status":"publish","type":"post","link":"https:\/\/acriticatrends.audiencelabs.com.br\/13o-salario-antecipado-aposentados-sao-avisados-sobre-liberacao-no-aplicativo-meu-inss\/","title":{"rendered":"13\u00ba sal\u00e1rio antecipado: aposentados s\u00e3o avisados sobre libera\u00e7\u00e3o no aplicativo meu INSS"},"content":{"rendered":"\n<p>Aposentados, pensionistas e benefici\u00e1rios do Instituto Nacional do Seguro Social (INSS) receberam uma atualiza\u00e7\u00e3o importante. Os cerca de 35,2 milh\u00f5es de contemplados j\u00e1 podem consultar a antecipa\u00e7\u00e3o do 13\u00ba sal\u00e1rio por meio aplicativo Meu INSS, dispon\u00edvel para celulares e tablets, ou no site gov.br\/meuinss.<\/p>\n\n\n\n<p>Conforme consta no calend\u00e1rio, a primeira parcela ser\u00e1 paga de 24 de abril a 8 de maio, enquanto a segunda parcela vai de 25 de maio a 8 de junho. Com a antecipa\u00e7\u00e3o, o Governo Federal espera injetar R$ 78,2 bilh\u00f5es na economia neste primeiro semestre do ano.<\/p>\n\n\n\n<p>Como de praxe, as datas dos pagamentos s\u00e3o definidas com base no d\u00edgito final do N\u00famero de Inscri\u00e7\u00e3o Social (NIS) e tamb\u00e9m na renda do benefici\u00e1rio. Quem ganha s\u00f3 o sal\u00e1rio m\u00ednimo come\u00e7a a receber antes de quem recebe mais que o valor-base.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/04\/58685ddf-9bca-46e3-9b3f-2e2fd43fa298-1024x613.jpg\" alt=\"\" class=\"wp-image-6390\" srcset=\"https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/04\/58685ddf-9bca-46e3-9b3f-2e2fd43fa298-1024x613.jpg 1024w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/04\/58685ddf-9bca-46e3-9b3f-2e2fd43fa298-300x180.jpg 300w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/04\/58685ddf-9bca-46e3-9b3f-2e2fd43fa298-768x460.jpg 768w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/04\/58685ddf-9bca-46e3-9b3f-2e2fd43fa298-750x449.jpg 750w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/04\/58685ddf-9bca-46e3-9b3f-2e2fd43fa298-1140x682.jpg 1140w, https:\/\/acriticatrends.audiencelabs.com.br\/wp-content\/uploads\/2026\/04\/58685ddf-9bca-46e3-9b3f-2e2fd43fa298.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Divulga\u00e7\u00e3o\/INSS<\/figcaption><\/figure>\n<\/div>\n\n\n<p>A antecipa\u00e7\u00e3o do abono foi oficializada ap\u00f3s a assinatura do decreto por parte do presidente Luiz In\u00e1cio Lula da Silva (PT). Esse \u00e9 o s\u00e9timo ano seguido em que os segurados recebem o d\u00e9cimo antes das datas tradicionais, em agosto e dezembro.<\/p>\n\n\n\n<p>Os dados mais recentes apontam que 23,3 milh\u00f5es dos segurados do INSS ganham at\u00e9 um sal\u00e1rio m\u00ednimo por m\u00eas. Outros 11,9 milh\u00f5es recebem acima do piso nacional, sendo 13,7 mil al\u00e9m do teto da Previd\u00eancia Social, que \u00e9 de R$ 8.475,55.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira o calend\u00e1rio da primeira parcela do 13\u00b0 sal\u00e1rio antecipado do INSS:<\/h2>\n\n\n\n<p><strong>Para benef\u00edcios iguais ao sal\u00e1rio m\u00ednimo<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Final do benef\u00edcio 1: 24 de abril<\/li>\n\n\n\n<li>Final do benef\u00edcio 2: 27 de abril<\/li>\n\n\n\n<li>Final do benef\u00edcio 3: 28 de abril<\/li>\n\n\n\n<li>Final do benef\u00edcio 4: 29 de abril<\/li>\n\n\n\n<li>Final do benef\u00edcio 5: 30 de abril<\/li>\n\n\n\n<li>Final do benef\u00edcio 6: 4 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 7: 5 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 8: 6 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 9: 7 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 0: 8 de maio<\/li>\n<\/ul>\n\n\n\n<p><strong>Para benef\u00edcios acima do sal\u00e1rio m\u00ednimo<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Final do benef\u00edcio 1 e 6: 4 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 2 e 7: 5 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 3 e 8: 6 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 4 e 9: 7 de maio<\/li>\n\n\n\n<li>Final do benef\u00edcio 5 e 0: 8 de maio<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aposentados, pensionistas e benefici\u00e1rios do Instituto Nacional do Seguro Social (INSS) receberam uma atualiza\u00e7\u00e3o importante. Os cerca de 35,2 milh\u00f5es de contemplados j\u00e1 podem consultar a antecipa\u00e7\u00e3o do 13\u00ba sal\u00e1rio por meio aplicativo Meu INSS, dispon\u00edvel para celulares e tablets, ou no site gov.br\/meuinss. Conforme consta no calend\u00e1rio, a primeira parcela ser\u00e1 paga de 24 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":5145,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[55],"tags":[],"class_list":["post-8098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trends"],"_links":{"self":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=8098"}],"version-history":[{"count":1,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8098\/revisions"}],"predecessor-version":[{"id":8099,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8098\/revisions\/8099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/5145"}],"wp:attachment":[{"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=8098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=8098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acriticatrends.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=8098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}